{"id":1634,"date":"2022-10-03T14:15:05","date_gmt":"2022-10-03T14:15:05","guid":{"rendered":"https:\/\/jlarce.com\/privacidad\/"},"modified":"2022-10-03T14:15:05","modified_gmt":"2022-10-03T14:15:05","slug":"privacidad","status":"publish","type":"page","link":"https:\/\/jlarce.com\/en\/privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"<h3>INTRODUCCI\u00d3N<\/h3>\n<p>En Jlarce, sensibilizados con las necesidades de los usuarios de Internet y conscientes de la importancia de la rigurosa privacidad de la informaci\u00f3n personal que nos conf\u00edan, incluimos esta declaraci\u00f3n de privacidad con el objeto de que seas consciente de la pol\u00edtica en el tratamiento de los datos personales que obtiene de sus visitantes y usuarios.<\/p><p>Como usuario, aceptas estas condiciones por el mero hecho de leer, visualizar o navegar en el sitio. De no aceptarlas, debes abandonar el sitio, sin hacer uso alguno de \u00e9l y su contenido, y sin acceder a las p\u00e1ginas enlazadas.<\/p>\n<h3 id='responsable'>RESPONSABLE DEL TRATAMIENTO DE DATOS<\/h3>\n<p>El titular del sitio y responsable del tratamiento de datos es Jose Luis, con DNI , para contactar puedes utilizar la direcci\u00f3n de correo electr\u00f3nico <a href=\"mailto:&#106;ose-&#108;u&#105;&#115;_&#50;2&#64;out&#108;o&#111;&#107;.co&#109;\">jo&#115;e-l&#117;&#105;&#115;_22&#64;o&#117;tl&#111;&#111;k.c&#111;m<\/a> o correo postal a 13, Rue del Percebe de Madrid.<\/p>\n<h3 id='finalidad'>FINALIDAD DEL TRATAMIENTO DE DATOS<\/h3>\n<p>En nuestros sitios web, existen unos apartados espec\u00edficos donde puedes anotar tus datos para recibir informaci\u00f3n sobre actualizaciones de nuestra web y de algunos los programas que se distribuyen. Nosotros te aseguramos que la informaci\u00f3n que nos facilites ser\u00e1 gestionada de forma totalmente confidencial.<\/p><p>Los datos se almacenar\u00e1n mientras exista previsi\u00f3n de su uso para el fin por el que fueron recabados.<\/p><p>No se realizan tomas de decisiones automatizadas con tus datos.<\/p><p>La web puede utilizar cookies, consulta nuestra <a href=\"https:\/\/jlarce.com\/en\/cookies\/\">pol\u00edtica de cookies<\/a>.<\/p>\n<h3 id='legitimacion'>LEGITIMACI\u00d3N DEL TRATAMIENTO DE DATOS<\/h3>\n<p>El uso de tus datos se realiza porque nos das tu consentimiento para usar los que nos proporcionas en los formularios para un uso espec\u00edfico que se indica en cada uno de ellos. Tus datos solo son necesarios para los usos concretos por los que se te solicitan, si no nos los facilitas, esos servicios no son posibles.<\/p>\n<h3 id='transferencia'>TRANSFERENCIAS Y CESIONES DE DATOS<\/h3>\n<p>Existe un compromiso firme por nuestra parte de que los datos que proporcione a Jlarce, no ser\u00e1n vendidos ni cedidos a terceras personas sin el previo consentimiento del interesado bajo ning\u00fan concepto o circunstancia, salvo consentimiento expreso u obligaci\u00f3n legal.<\/p><p>Nuestro sitio web contiene enlaces hacia sitios web de terceros. Jlarce no se hace responsable por las pol\u00edticas y pr\u00e1cticas de privacidad de estos otros sitios.<\/p>\n<h3 id='derechos'>DERECHOS DE LOS INTERESADOS<\/h3>\n<p>Tienes el derecho de acceder a la informaci\u00f3n que sobre tu persona est\u00e1 almacenada en nuestras bases de datos, rectificarla si existiera alguna errata, suprimirla, limitarla, oponerte a su tratamiento y retirar tu consentimiento si ese es tu deseo. Para ello simplemente debes escribir un e-mail a la direcci\u00f3n de correo electr\u00f3nico <a href=\"mailto:jose-lu&#105;s_&#50;&#50;@outloo&#107;&#46;c&#111;&#109;\">jos&#101;&#45;l&#117;&#105;s_&#50;&#50;&#64;&#111;ut&#108;&#111;&#111;&#107;&#46;c&#111;m<\/a> donde te atenderemos gustosamente cualquier consulta, comentario o aclaraci\u00f3n requerida al respecto.<\/p><p>Para mayor informaci\u00f3n sobre temas relacionados, el sitio de referencia en la Red espa\u00f1ola es la <a href=\"https:\/\/www.agpd.es\/\">Agencia de Protecci\u00f3n de Datos<\/a>, donde tienes derecho a reclamar.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1634","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edtica de privacidad - JL Arce 2026<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jlarce.com\/en\/privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad - JL Arce 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jlarce.com\/en\/privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"JL Arce 2026\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jlarce.com\/privacidad\/\",\"url\":\"https:\/\/jlarce.com\/privacidad\/\",\"name\":\"Pol\u00edtica de privacidad - JL Arce 2026\",\"isPartOf\":{\"@id\":\"https:\/\/jlarce.com\/#website\"},\"datePublished\":\"2022-10-03T14:15:05+00:00\",\"dateModified\":\"2022-10-03T14:15:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/jlarce.com\/privacidad\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jlarce.com\/privacidad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jlarce.com\/privacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/jlarce.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jlarce.com\/#website\",\"url\":\"https:\/\/jlarce.com\/\",\"name\":\"JL Arce 2026\",\"description\":\"Fotograf\u00eda y v\u00eddeo profesional\",\"publisher\":{\"@id\":\"https:\/\/jlarce.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jlarce.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jlarce.com\/#organization\",\"name\":\"JL Arce 2026\",\"url\":\"https:\/\/jlarce.com\/\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/jos-luis-martinez-arce-231012179\/\",\"https:\/\/www.instagram.com\/jlarce_\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/jlarce.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jlarce.com\/wp-content\/uploads\/2020\/12\/Logo-JL-Arce-3.png\",\"contentUrl\":\"https:\/\/jlarce.com\/wp-content\/uploads\/2020\/12\/Logo-JL-Arce-3.png\",\"width\":1181,\"height\":1181,\"caption\":\"JL Arce  2026\"},\"image\":{\"@id\":\"https:\/\/jlarce.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad - JL Arce 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jlarce.com\/en\/privacidad\/","og_locale":"en_GB","og_type":"article","og_title":"Pol\u00edtica de privacidad - JL Arce 2026","og_url":"https:\/\/jlarce.com\/en\/privacidad\/","og_site_name":"JL Arce 2026","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jlarce.com\/privacidad\/","url":"https:\/\/jlarce.com\/privacidad\/","name":"Pol\u00edtica de privacidad - JL Arce 2026","isPartOf":{"@id":"https:\/\/jlarce.com\/#website"},"datePublished":"2022-10-03T14:15:05+00:00","dateModified":"2022-10-03T14:15:05+00:00","breadcrumb":{"@id":"https:\/\/jlarce.com\/privacidad\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jlarce.com\/privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jlarce.com\/privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jlarce.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de privacidad"}]},{"@type":"WebSite","@id":"https:\/\/jlarce.com\/#website","url":"https:\/\/jlarce.com\/","name":"JL Arce 2026","description":"Fotograf\u00eda y v\u00eddeo profesional","publisher":{"@id":"https:\/\/jlarce.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jlarce.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/jlarce.com\/#organization","name":"JL Arce 2026","url":"https:\/\/jlarce.com\/","sameAs":["https:\/\/www.linkedin.com\/in\/jos-luis-martinez-arce-231012179\/","https:\/\/www.instagram.com\/jlarce_\/"],"logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/jlarce.com\/#\/schema\/logo\/image\/","url":"https:\/\/jlarce.com\/wp-content\/uploads\/2020\/12\/Logo-JL-Arce-3.png","contentUrl":"https:\/\/jlarce.com\/wp-content\/uploads\/2020\/12\/Logo-JL-Arce-3.png","width":1181,"height":1181,"caption":"JL Arce  2026"},"image":{"@id":"https:\/\/jlarce.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jlarce.com\/en\/wp-json\/wp\/v2\/pages\/1634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jlarce.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jlarce.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jlarce.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jlarce.com\/en\/wp-json\/wp\/v2\/comments?post=1634"}],"version-history":[{"count":0,"href":"https:\/\/jlarce.com\/en\/wp-json\/wp\/v2\/pages\/1634\/revisions"}],"wp:attachment":[{"href":"https:\/\/jlarce.com\/en\/wp-json\/wp\/v2\/media?parent=1634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}